{"id":114,"count":12,"description":"","link":"https:\/\/crisscrossauto.com\/uk\/product-category\/make\/chery\/exceed\/","name":"Exceed","slug":"exceed","taxonomy":"product_cat","parent":104,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Exceed Archives - Crisscross Auto<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/crisscrossauto.com\/uk\/product-category\/make\/chery\/exceed\/\" \/>\n<meta property=\"og:locale\" content=\"uk_UA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Exceed Archives - Crisscross Auto\" \/>\n<meta property=\"og:url\" content=\"https:\/\/crisscrossauto.com\/uk\/product-category\/make\/chery\/exceed\/\" \/>\n<meta property=\"og:site_name\" content=\"Crisscross Auto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CCAuto1123\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/crisscrossauto.com\\\/product-category\\\/make\\\/chery\\\/exceed\\\/\",\"url\":\"https:\\\/\\\/crisscrossauto.com\\\/product-category\\\/make\\\/chery\\\/exceed\\\/\",\"name\":\"Exceed Archives - Crisscross Auto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/crisscrossauto.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/crisscrossauto.com\\\/product-category\\\/make\\\/chery\\\/exceed\\\/#breadcrumb\"},\"inLanguage\":\"uk\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/crisscrossauto.com\\\/product-category\\\/make\\\/chery\\\/exceed\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/crisscrossauto.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Make\",\"item\":\"https:\\\/\\\/crisscrossauto.com\\\/product-category\\\/make\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Chery\",\"item\":\"https:\\\/\\\/crisscrossauto.com\\\/product-category\\\/make\\\/chery\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Exceed\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/crisscrossauto.com\\\/#website\",\"url\":\"https:\\\/\\\/crisscrossauto.com\\\/\",\"name\":\"Crisscross Auto\",\"description\":\"Your Gateway to China Car Selections\",\"publisher\":{\"@id\":\"https:\\\/\\\/crisscrossauto.com\\\/#organization\"},\"alternateName\":\"CrissCross\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/crisscrossauto.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"uk\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/crisscrossauto.com\\\/#organization\",\"name\":\"Crisscross Auto\",\"url\":\"https:\\\/\\\/crisscrossauto.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"uk\",\"@id\":\"https:\\\/\\\/crisscrossauto.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/crisscrossauto.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/logo-original.png\",\"contentUrl\":\"https:\\\/\\\/crisscrossauto.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/logo-original.png\",\"width\":300,\"height\":300,\"caption\":\"Crisscross Auto\"},\"image\":{\"@id\":\"https:\\\/\\\/crisscrossauto.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=61553482477688\",\"https:\\\/\\\/x.com\\\/CCAuto1123\",\"https:\\\/\\\/www.pinterest.com\\\/ccauto1123\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Exceed Archives - Crisscross Auto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/crisscrossauto.com\/uk\/product-category\/make\/chery\/exceed\/","og_locale":"uk_UA","og_type":"article","og_title":"Exceed Archives - Crisscross Auto","og_url":"https:\/\/crisscrossauto.com\/uk\/product-category\/make\/chery\/exceed\/","og_site_name":"Crisscross Auto","twitter_card":"summary_large_image","twitter_site":"@CCAuto1123","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/crisscrossauto.com\/product-category\/make\/chery\/exceed\/","url":"https:\/\/crisscrossauto.com\/product-category\/make\/chery\/exceed\/","name":"Exceed Archives - Crisscross Auto","isPartOf":{"@id":"https:\/\/crisscrossauto.com\/#website"},"breadcrumb":{"@id":"https:\/\/crisscrossauto.com\/product-category\/make\/chery\/exceed\/#breadcrumb"},"inLanguage":"uk"},{"@type":"BreadcrumbList","@id":"https:\/\/crisscrossauto.com\/product-category\/make\/chery\/exceed\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/crisscrossauto.com\/"},{"@type":"ListItem","position":2,"name":"Make","item":"https:\/\/crisscrossauto.com\/product-category\/make\/"},{"@type":"ListItem","position":3,"name":"Chery","item":"https:\/\/crisscrossauto.com\/product-category\/make\/chery\/"},{"@type":"ListItem","position":4,"name":"Exceed"}]},{"@type":"WebSite","@id":"https:\/\/crisscrossauto.com\/#website","url":"https:\/\/crisscrossauto.com\/","name":"Crisscross Auto","description":"Your Gateway to China Car Selections","publisher":{"@id":"https:\/\/crisscrossauto.com\/#organization"},"alternateName":"CrissCross","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/crisscrossauto.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"uk"},{"@type":"Organization","@id":"https:\/\/crisscrossauto.com\/#organization","name":"Crisscross Auto","url":"https:\/\/crisscrossauto.com\/","logo":{"@type":"ImageObject","inLanguage":"uk","@id":"https:\/\/crisscrossauto.com\/#\/schema\/logo\/image\/","url":"https:\/\/crisscrossauto.com\/wp-content\/uploads\/2023\/11\/logo-original.png","contentUrl":"https:\/\/crisscrossauto.com\/wp-content\/uploads\/2023\/11\/logo-original.png","width":300,"height":300,"caption":"Crisscross Auto"},"image":{"@id":"https:\/\/crisscrossauto.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61553482477688","https:\/\/x.com\/CCAuto1123","https:\/\/www.pinterest.com\/ccauto1123"]}]}},"_links":{"self":[{"href":"https:\/\/crisscrossauto.com\/uk\/wp-json\/wp\/v2\/product_cat\/114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/crisscrossauto.com\/uk\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/crisscrossauto.com\/uk\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/crisscrossauto.com\/uk\/wp-json\/wp\/v2\/product_cat\/104"}],"wp:post_type":[{"href":"https:\/\/crisscrossauto.com\/uk\/wp-json\/wp\/v2\/product?product_cat=114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}